{"id":9945,"date":"2026-08-03T13:30:57","date_gmt":"2026-08-03T14:30:57","guid":{"rendered":"https:\/\/ciit-software.com\/?page_id=9945"},"modified":"2026-08-12T14:20:20","modified_gmt":"2026-08-12T15:20:20","slug":"wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh","status":"publish","type":"page","link":"https:\/\/ciit-software.com\/en\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\/","title":{"rendered":"WFT GmbH digitalisiert die N\u00e4hrstoffzugabe in Weinkellern zusammen mit der CIIT GmbH"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9945\" class=\"elementor elementor-9945\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0fed118 e-con-full e-flex e-con e-parent\" data-id=\"0fed118\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d1df060 e-con-full e-flex e-con e-child\" data-id=\"d1df060\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06c45d9 elementor-widget elementor-widget-text-editor\" data-id=\"06c45d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>WFT GmbH, together with CIIT GmbH, enables the automated dosing of nutrients in the food industry.<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fce5577 elementor-widget elementor-widget-text-editor\" data-id=\"fce5577\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>WFT GmbH, based in Klosterneuburg near Vienna, has jointly developed a hardware and software solution for the food industry with CIIT GmbH.\u00a0<\/p><p>The company has specialized in wine cellars with its resulting product VinPilot\u00ae.\u00a0<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-205a5e5 e-flex e-con-boxed e-con e-child\" data-id=\"205a5e5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8f86f9 elementor-hidden-laptop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"e8f86f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT-1024x576.png\" class=\"attachment-large size-large wp-image-10594\" alt=\"\" srcset=\"https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT-1024x576.png 1024w, https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT-300x169.png 300w, https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT-768x432.png 768w, https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT-18x10.png 18w, https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ccb859 elementor-hidden-desktop elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"5ccb859\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT-1024x576.png\" class=\"attachment-large size-large wp-image-10594\" alt=\"\" srcset=\"https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT-1024x576.png 1024w, https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT-300x169.png 300w, https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT-768x432.png 768w, https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT-18x10.png 18w, https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT.png 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>WFT GmbH erm\u00f6glicht mit der CIIT GmbH gemeinsam die automatisierte Dosierung von N\u00e4hrstoffen in der Lebensmittelindustrie Die WFT GmbH mit Sitz in Klosterneuburg bei Wien hat mit der CIIT GmbH gemeinsam eine Hard- und Softwarel\u00f6sung entwickelt f\u00fcr die Lebensmittelindustrie.\u00a0 Das Unternehmen hat sich mit dem daraus resultierenden Produkt VinPilot\u00ae auf Weinkeller spezialisiert.\u00a0 \u00a0<\/p>","protected":false},"author":18,"featured_media":10594,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-9945","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WFT GmbH digitalisiert die N\u00e4hrstoffzugabe in Weinkellern zusammen mit der CIIT GmbH - CIIT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ciit-software.com\/en\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WFT GmbH digitalisiert die N\u00e4hrstoffzugabe in Weinkellern zusammen mit der CIIT GmbH - CIIT\" \/>\n<meta property=\"og:description\" content=\"WFT GmbH erm\u00f6glicht mit der CIIT GmbH gemeinsam die automatisierte Dosierung von N\u00e4hrstoffen in der Lebensmittelindustrie Die WFT GmbH mit Sitz in Klosterneuburg bei Wien hat mit der CIIT GmbH gemeinsam eine Hard- und Softwarel\u00f6sung entwickelt f\u00fcr die Lebensmittelindustrie.\u00a0 Das Unternehmen hat sich mit dem daraus resultierenden Produkt VinPilot\u00ae auf Weinkeller spezialisiert.\u00a0 \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ciit-software.com\/en\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\/\" \/>\n<meta property=\"og:site_name\" content=\"CIIT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CIITIndividualsoftware\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-12T15:20:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CIIT_at\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ciit-software.com\\\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\\\/\",\"url\":\"https:\\\/\\\/ciit-software.com\\\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\\\/\",\"name\":\"WFT GmbH digitalisiert die N\u00e4hrstoffzugabe in Weinkellern zusammen mit der CIIT GmbH - CIIT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ciit-software.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ciit-software.com\\\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ciit-software.com\\\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ciit-software.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Vinpilot-x-CIIT.png\",\"datePublished\":\"2026-08-03T14:30:57+00:00\",\"dateModified\":\"2026-08-12T15:20:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ciit-software.com\\\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ciit-software.com\\\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ciit-software.com\\\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ciit-software.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Vinpilot-x-CIIT.png\",\"contentUrl\":\"https:\\\/\\\/ciit-software.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Vinpilot-x-CIIT.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ciit-software.com\\\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ciit-software.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WFT GmbH digitalisiert die N\u00e4hrstoffzugabe in Weinkellern zusammen mit der CIIT GmbH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ciit-software.com\\\/#website\",\"url\":\"https:\\\/\\\/ciit-software.com\\\/\",\"name\":\"CIIT\",\"description\":\"Individual Software\",\"publisher\":{\"@id\":\"https:\\\/\\\/ciit-software.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ciit-software.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ciit-software.com\\\/#organization\",\"name\":\"CIIT GmbH\",\"url\":\"https:\\\/\\\/ciit-software.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ciit-software.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ciit-software.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-CIIT_Logo_Software-Develoment.png\",\"contentUrl\":\"https:\\\/\\\/ciit-software.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-CIIT_Logo_Software-Develoment.png\",\"width\":512,\"height\":512,\"caption\":\"CIIT GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/ciit-software.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CIITIndividualsoftware\",\"https:\\\/\\\/x.com\\\/CIIT_at\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WFT GmbH digitalisiert die N\u00e4hrstoffzugabe in Weinkellern zusammen mit der CIIT GmbH - CIIT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ciit-software.com\/en\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\/","og_locale":"en_US","og_type":"article","og_title":"WFT GmbH digitalisiert die N\u00e4hrstoffzugabe in Weinkellern zusammen mit der CIIT GmbH - CIIT","og_description":"WFT GmbH erm\u00f6glicht mit der CIIT GmbH gemeinsam die automatisierte Dosierung von N\u00e4hrstoffen in der Lebensmittelindustrie Die WFT GmbH mit Sitz in Klosterneuburg bei Wien hat mit der CIIT GmbH gemeinsam eine Hard- und Softwarel\u00f6sung entwickelt f\u00fcr die Lebensmittelindustrie.\u00a0 Das Unternehmen hat sich mit dem daraus resultierenden Produkt VinPilot\u00ae auf Weinkeller spezialisiert.\u00a0 \u00a0","og_url":"https:\/\/ciit-software.com\/en\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\/","og_site_name":"CIIT","article_publisher":"https:\/\/www.facebook.com\/CIITIndividualsoftware","article_modified_time":"2026-08-12T15:20:20+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@CIIT_at","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ciit-software.com\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\/","url":"https:\/\/ciit-software.com\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\/","name":"WFT GmbH digitalisiert die N\u00e4hrstoffzugabe in Weinkellern zusammen mit der CIIT GmbH - CIIT","isPartOf":{"@id":"https:\/\/ciit-software.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ciit-software.com\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\/#primaryimage"},"image":{"@id":"https:\/\/ciit-software.com\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\/#primaryimage"},"thumbnailUrl":"https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT.png","datePublished":"2026-08-03T14:30:57+00:00","dateModified":"2026-08-12T15:20:20+00:00","breadcrumb":{"@id":"https:\/\/ciit-software.com\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ciit-software.com\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ciit-software.com\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\/#primaryimage","url":"https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT.png","contentUrl":"https:\/\/ciit-software.com\/wp-content\/uploads\/2026\/08\/Vinpilot-x-CIIT.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/ciit-software.com\/wft-gmbh-digitalisiert-die-naehrstoffzugabe-in-weinkellern-zusammen-mit-der-ciit-gmbh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ciit-software.com\/"},{"@type":"ListItem","position":2,"name":"WFT GmbH digitalisiert die N\u00e4hrstoffzugabe in Weinkellern zusammen mit der CIIT GmbH"}]},{"@type":"WebSite","@id":"https:\/\/ciit-software.com\/#website","url":"https:\/\/ciit-software.com\/","name":"CIIT","description":"Individual software","publisher":{"@id":"https:\/\/ciit-software.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ciit-software.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ciit-software.com\/#organization","name":"CIIT GmbH","url":"https:\/\/ciit-software.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ciit-software.com\/#\/schema\/logo\/image\/","url":"https:\/\/ciit-software.com\/wp-content\/uploads\/2024\/01\/cropped-CIIT_Logo_Software-Develoment.png","contentUrl":"https:\/\/ciit-software.com\/wp-content\/uploads\/2024\/01\/cropped-CIIT_Logo_Software-Develoment.png","width":512,"height":512,"caption":"CIIT GmbH"},"image":{"@id":"https:\/\/ciit-software.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CIITIndividualsoftware","https:\/\/x.com\/CIIT_at"]}]}},"_links":{"self":[{"href":"https:\/\/ciit-software.com\/en\/wp-json\/wp\/v2\/pages\/9945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ciit-software.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ciit-software.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ciit-software.com\/en\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/ciit-software.com\/en\/wp-json\/wp\/v2\/comments?post=9945"}],"version-history":[{"count":10,"href":"https:\/\/ciit-software.com\/en\/wp-json\/wp\/v2\/pages\/9945\/revisions"}],"predecessor-version":[{"id":10600,"href":"https:\/\/ciit-software.com\/en\/wp-json\/wp\/v2\/pages\/9945\/revisions\/10600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ciit-software.com\/en\/wp-json\/wp\/v2\/media\/10594"}],"wp:attachment":[{"href":"https:\/\/ciit-software.com\/en\/wp-json\/wp\/v2\/media?parent=9945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}